{"id":296,"date":"2017-02-23T13:54:10","date_gmt":"2017-02-23T12:54:10","guid":{"rendered":"https:\/\/www.carnicaspedrogomez.es\/recetas\/?p=296"},"modified":"2017-02-23T13:54:10","modified_gmt":"2017-02-23T12:54:10","slug":"recetas-ninos-cachopo","status":"publish","type":"post","link":"https:\/\/www.carnicaspedrogomez.es\/recetas\/recetas-ninos-cachopo\/","title":{"rendered":"Receta para ni\u00f1os: \u00a1cachopo!"},"content":{"rendered":"<div id=\"attachment_297\" style=\"width: 990px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/palomadelarica.com\/2015\/07\/16\/cachopo\/\"><img aria-describedby=\"caption-attachment-297\" loading=\"lazy\" class=\"size-full wp-image-297\" src=\"https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-content\/uploads\/2017\/02\/cachopo.jpg\" alt=\"\" width=\"980\" height=\"653\" srcset=\"https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-content\/uploads\/2017\/02\/cachopo.jpg 980w, https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-content\/uploads\/2017\/02\/cachopo-300x200.jpg 300w, https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-content\/uploads\/2017\/02\/cachopo-768x512.jpg 768w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/a><p id=\"caption-attachment-297\" class=\"wp-caption-text\">Foto: Paloma de la Rica<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Hay pocas recetas tan sencillas y que despierten tanta controversia y admiraci\u00f3n, como el <a href=\"http:\/\/palomadelarica.com\/2015\/07\/16\/cachopo\/\" target=\"_blank\">cachopo<\/a>, que se hace con\u00a0un par de filetes de ternera rellenos (como si fuera un bocadillo)\u00a0de jam\u00f3n serrano y queso. Parece sencillo, \u00bfverdad? Lo es, aunque su preparaci\u00f3n tiene su truco, puesto que hay que estirar bien la carne y tener cuidado al fre\u00edrlo, aunque estamos seguros que si sigues paso a paso la receta <a href=\"http:\/\/palomadelarica.com\/2015\/07\/16\/cachopo\/\" target=\"_blank\">cachopo <\/a>de Paloma de la Rica, te\u00a0va a salir un plato delicioso.<\/p>\n<p>Puedes rellenarlo con lo que t\u00fa quieras&#8230;y ah\u00ed empieza el debate porque, para los asturianos, no todo el monte es cachopo. Pero como ahora estamos en casa, podemos disfrutar de un gran cachopo (perfecto por su tama\u00f1o para ser compartido) con un poco de sidra, unos pimientos y acordarnos as\u00ed del \u00faltimo fin de semana que pasamos en Asturias&#8230; \u00a1y planear el siguiente! Ese donde, entonces s\u00ed, probaremos el aut\u00e9ntico cachopo asturiano.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[53],"tags":[153,143,23,154,80,25,26,34],"_links":{"self":[{"href":"https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-json\/wp\/v2\/posts\/296"}],"collection":[{"href":"https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-json\/wp\/v2\/comments?post=296"}],"version-history":[{"count":1,"href":"https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-json\/wp\/v2\/posts\/296\/revisions"}],"predecessor-version":[{"id":298,"href":"https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-json\/wp\/v2\/posts\/296\/revisions\/298"}],"wp:attachment":[{"href":"https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-json\/wp\/v2\/media?parent=296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-json\/wp\/v2\/categories?post=296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carnicaspedrogomez.es\/recetas\/wp-json\/wp\/v2\/tags?post=296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}